{"id":3057,"date":"2020-03-25T13:47:45","date_gmt":"2022-02-01T13:08:00","guid":{"rendered":"https:\/\/www.hazadellino.com\/?post_type=product&#038;p=3057"},"modified":"2024-05-22T08:15:51","modified_gmt":"2024-05-22T07:15:51","slug":"ollero-joven-2","status":"publish","type":"product","link":"https:\/\/www.hazadellino.com\/en\/la-alpujarra\/ollero-joven-2\/","title":{"rendered":"Ollero Joven"},"content":{"rendered":"<p>Ollero Joven (silveretikett): Ungt r\u00f6tt vin. Tempranillo monovarietal.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ungt r\u00f6tt vin. Tempranillo monovarietal.<\/p>","protected":false},"featured_media":2316,"template":"","meta":{"_mbp_gutenberg_autopost":false},"product_brand":[],"product_cat":[142],"product_tag":[],"class_list":{"0":"post-3057","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vinos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ollero Joven - Restaurante &amp; Bodega Haza del Lino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hazadellino.com\/en\/la-alpujarra\/ollero-joven-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ollero Joven - Restaurante &amp; Bodega Haza del Lino\" \/>\n<meta property=\"og:description\" content=\"Ungt r\u00f6tt vin. Tempranillo monovarietal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hazadellino.com\/en\/la-alpujarra\/ollero-joven-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurante &amp; Bodega Haza del Lino\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-22T07:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/ollero-2016-copa@2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1484\" \/>\n\t<meta property=\"og:image:height\" content=\"1492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/\",\"url\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/\",\"name\":\"Ollero Joven - Restaurante &amp; Bodega Haza del Lino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hazadellino.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/ollero-2016-copa@2x.png\",\"datePublished\":\"2022-02-01T13:08:00+00:00\",\"dateModified\":\"2024-05-22T07:15:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hazadellino.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/ollero-2016-copa@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.hazadellino.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/ollero-2016-copa@2x.png\",\"width\":1484,\"height\":1492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/la-alpujarra\\\/ollero-joven-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hazadellino.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda Haza del Lino\",\"item\":\"https:\\\/\\\/www.hazadellino.com\\\/tienda-haza-del-lino\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ollero Joven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hazadellino.com\\\/\",\"name\":\"Restaurante &amp; Bodega Haza del Lino\",\"description\":\"Pasea por los sabores y paisajes &uacute;nicos de la Alpujarra con Haza del Lino. Descubrir la aut&eacute;ntica esencia culinaria y vin&iacute;cola de esta regi&oacute;n ic&oacute;nica.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hazadellino.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#organization\",\"name\":\"Restaurante &amp; Bodega Haza del Lino\",\"url\":\"https:\\\/\\\/www.hazadellino.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hazadellino.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logotipo_haza-del-lino@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.hazadellino.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logotipo_haza-del-lino@2x.png\",\"width\":512,\"height\":512,\"caption\":\"Restaurante &amp; Bodega Haza del Lino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hazadellino.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ollero Joven - Restaurante &amp; Bodega Haza del Lino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hazadellino.com\/en\/la-alpujarra\/ollero-joven-2\/","og_locale":"en_GB","og_type":"article","og_title":"Ollero Joven - Restaurante &amp; Bodega Haza del Lino","og_description":"Ungt r\u00f6tt vin. Tempranillo monovarietal.","og_url":"https:\/\/www.hazadellino.com\/en\/la-alpujarra\/ollero-joven-2\/","og_site_name":"Restaurante &amp; Bodega Haza del Lino","article_modified_time":"2024-05-22T07:15:51+00:00","og_image":[{"width":1484,"height":1492,"url":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/ollero-2016-copa@2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/","url":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/","name":"Ollero Joven - Restaurante &amp; Bodega Haza del Lino","isPartOf":{"@id":"https:\/\/www.hazadellino.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/#primaryimage"},"image":{"@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/ollero-2016-copa@2x.png","datePublished":"2022-02-01T13:08:00+00:00","dateModified":"2024-05-22T07:15:51+00:00","breadcrumb":{"@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/#primaryimage","url":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/ollero-2016-copa@2x.png","contentUrl":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/ollero-2016-copa@2x.png","width":1484,"height":1492},{"@type":"BreadcrumbList","@id":"https:\/\/www.hazadellino.com\/la-alpujarra\/ollero-joven-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hazadellino.com\/"},{"@type":"ListItem","position":2,"name":"Tienda Haza del Lino","item":"https:\/\/www.hazadellino.com\/tienda-haza-del-lino\/"},{"@type":"ListItem","position":3,"name":"Ollero Joven"}]},{"@type":"WebSite","@id":"https:\/\/www.hazadellino.com\/#website","url":"https:\/\/www.hazadellino.com\/","name":"Restaurante &amp; Bodega Haza del Lino","description":"Pasea por los sabores y paisajes &uacute;nicos de la Alpujarra con Haza del Lino. Descubrir la aut&eacute;ntica esencia culinaria y vin&iacute;cola de esta regi&oacute;n ic&oacute;nica.","publisher":{"@id":"https:\/\/www.hazadellino.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hazadellino.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.hazadellino.com\/#organization","name":"Restaurante &amp; Bodega Haza del Lino","url":"https:\/\/www.hazadellino.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.hazadellino.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/cropped-logotipo_haza-del-lino@2x.png","contentUrl":"https:\/\/www.hazadellino.com\/wp-content\/uploads\/2020\/03\/cropped-logotipo_haza-del-lino@2x.png","width":512,"height":512,"caption":"Restaurante &amp; Bodega Haza del Lino"},"image":{"@id":"https:\/\/www.hazadellino.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product\/3057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product\/3057\/revisions"}],"predecessor-version":[{"id":3061,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product\/3057\/revisions\/3061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/media\/2316"}],"wp:attachment":[{"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/media?parent=3057"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product_brand?post=3057"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product_cat?post=3057"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.hazadellino.com\/en\/wp-json\/wp\/v2\/product_tag?post=3057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}